{"id":301,"date":"2017-08-02T18:45:44","date_gmt":"2017-08-02T16:45:44","guid":{"rendered":"http:\/\/www.fechtklub.at\/wordpress\/?p=301"},"modified":"2026-06-12T22:29:41","modified_gmt":"2026-06-12T20:29:41","slug":"grossartige-ergebnisse-bei-der-oesterreichischen-jugendstaatsmeisterschaft-2017","status":"publish","type":"post","link":"http:\/\/www.fechtklub.at\/wordpress\/grossartige-ergebnisse-bei-der-oesterreichischen-jugendstaatsmeisterschaft-2017\/","title":{"rendered":"Gro\u00dfartige Ergebnisse bei der \u00d6sterreichischen Jugendstaatsmeisterschaft 2017"},"content":{"rendered":"<p>Ausgezeichnete Leistungen des Wiener Neudorfer Fechternachwuchses bei der Jugendstaatsmeisterschaft 2017 in V\u00f6cklabruck!<br \/>\nSowohl David Hertel als auch Victoria Hierath belegten im Florett in einem gro\u00dfen Starterfeld den hervorragenden achten Platz und erreichten damit eine Finalplatzierung. Das ist das beste Ergebnis eines Neudorfer Fechters bei einer Staatsmeisterschaft seit Jahren. Gratulation!<br \/>\nAber auch die anderen Neudorfer Starter fochten sehr gut und Oliver Schramm mit dem 27.Platz und David Weirich mit dem 29.Platz im Florettbewerb holten Ranglistenpunkte.<br \/>\nAls Draufgabe erk\u00e4mpften im Degen David Hertel den 11.Platz, David Weirich den 21.Platz (sein erstes gro\u00dfes Turnier) und Victoria Hierath den 17.Platz.<br \/>\nEin sehr sch\u00f6ner Saisonabschlu\u00df!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ausgezeichnete Leistungen des Wiener Neudorfer Fechternachwuchses bei der Jugendstaatsmeisterschaft 2017 in V\u00f6cklabruck! Sowohl David Hertel als auch Victoria Hierath belegten im Florett in einem gro\u00dfen Starterfeld den hervorragenden achten Platz und erreichten damit eine Finalplatzierung. Das ist das beste Ergebnis eines Neudorfer Fechters bei einer Staatsmeisterschaft seit Jahren. Gratulation! Aber auch die anderen Neudorfer Starter&#8230;<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","footnotes":""},"categories":[],"tags":[],"class_list":["post-301","post","type-post","status-publish","format-standard","hentry"],"_links":{"self":[{"href":"http:\/\/www.fechtklub.at\/wordpress\/wp-json\/wp\/v2\/posts\/301","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.fechtklub.at\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.fechtklub.at\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.fechtklub.at\/wordpress\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/www.fechtklub.at\/wordpress\/wp-json\/wp\/v2\/comments?post=301"}],"version-history":[{"count":3,"href":"http:\/\/www.fechtklub.at\/wordpress\/wp-json\/wp\/v2\/posts\/301\/revisions"}],"predecessor-version":[{"id":305,"href":"http:\/\/www.fechtklub.at\/wordpress\/wp-json\/wp\/v2\/posts\/301\/revisions\/305"}],"wp:attachment":[{"href":"http:\/\/www.fechtklub.at\/wordpress\/wp-json\/wp\/v2\/media?parent=301"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.fechtklub.at\/wordpress\/wp-json\/wp\/v2\/categories?post=301"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.fechtklub.at\/wordpress\/wp-json\/wp\/v2\/tags?post=301"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}